{"id":5556,"date":"2022-09-01T18:30:03","date_gmt":"2022-09-01T22:30:03","guid":{"rendered":"https:\/\/salonautomontreal.com\/maserati-levante-gt-2022-la-dolce-vita\/"},"modified":"2024-10-25T16:45:34","modified_gmt":"2024-10-25T20:45:34","slug":"maserati-levante-gt-2022-la-dolce-vita","status":"publish","type":"post","link":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/","title":{"rendered":"Maserati Levante GT 2022 : La Dolce Vita"},"content":{"rendered":"<p>Le Salon International de l\u2019Auto de Montr\u00e9al porte cette semaine bien son nom, puisqu\u2019il vous emm\u00e8ne en terre de Mod\u00e8ne, en Italie. C\u2019est en d\u00e9but de saison estivale que le Salon s\u2019est envol\u00e9 pour le Vieux Continent, et on a eu droit \u00e0 une balade \u00e0 bord d\u2019un VUS aux couleurs pour le moins flamboyantes\u00a0: le Maserati Levante, dans sa d\u00e9clinaison GT (hybride) est le v\u00e9hicule qui nous a permis de visiter la r\u00e9gion que plusieurs consid\u00e8rent comme Mecque de la voiture sportive.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10785 size-full\" src=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2022\/09\/dsc00100-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1706\" \/><\/p>\n<p><strong>Verrons-nous un mod\u00e8le hybride en sol canadien?<\/strong><\/p>\n<p>Au moment d\u2019\u00e9crire ces lignes, deux motorisations sont offertes pour le Maserati Levante au Canada. On parle tout d\u2019abord du plus commun des engins, soit le V6 turbocompress\u00e9 qui d\u00e9veloppe 345 chevaux, ainsi que le plus costaud V8 turbocompress\u00e9 qui d\u00e9veloppe quant \u00e0 lui 550 chevaux.\u00a0Bien que ces motorisations soient plus que respectables, on est tout de m\u00eame loin de la promesse environnementale faite par le constructeur, selon laquelle tous leurs bolides auront un mod\u00e8le qui adoptera une forme d\u2019\u00e9lectrification d\u2019ici 2025. Alors oui, on devrait \u00e9ventuellement voir une version hybride du Levante en sol canadien.<\/p>\n<p>L\u2019histoire est cependant toute autre en Europe, alors que plusieurs mod\u00e8les, comme le Levante, offrent d\u00e9j\u00e0 une version \u00e9lectrifi\u00e9e au sien de leur gamme respective. C\u2019est d\u2019ailleurs le cas du bolide \u00e0 l\u2019essai, alors qu\u2019on retrouvait sous le capot un engin de quatre cylindres de 2,0 litres de cylindr\u00e9e, auquel est jumel\u00e9 une motorisation hybride de 48 volts. La combinaison de ces deux engins permet la production de 330 chevaux, soit un nombre tr\u00e8s similaire \u00e0 la version uniquement \u00e0 essence que l\u2019on retrouve chez nous.<\/p>\n<p>Le net avantage que cette version procure est naturellement sa consommation d\u2019essence\u00a0: celle-ci avoisine les 8,1l\/100 km, en comparaison aux 13,2l\/100 km de la version que l\u2019on retrouve ici. Il est cependant bien de sp\u00e9cifier que les normes europ\u00e9ennes de consommation d\u2019essence sont plus g\u00e9n\u00e9reuses qu\u2019ici.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10795 size-full\" src=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2022\/09\/dsc00107-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1706\" \/><\/p>\n<p>Donn\u00e9es techniques et jargon scientifique de c\u00f4t\u00e9, le Levante GT Hybride que nous avons mis \u00e0 l\u2019essai \u00e9tait d\u2019un charme incontest\u00e9. La sonorit\u00e9 de son engin \u00e0 quatre cylindres \u00e9tait \u00e0 notre grande surprise tr\u00e8s enviable et la direction \u00e9tait pr\u00e9cise et inspirait confiance lors de la prise de virages. Puis, les 330 chevaux d\u00e9velopp\u00e9s par la motorisation hybride permettaient des acc\u00e9l\u00e9rations plus que franches et ce, m\u00eame en reprises. Dans les faits, on oublie avec beaucoup d\u2019aisance que l\u2019on se retrouve dans un produit dont beaucoup de composantes proviennent du groupe Stellantis.<\/p>\n<p><strong>Look et style \u00e0 l\u2019image de la r\u00e9gion<\/strong><\/p>\n<p>Bon, passons maintenant \u00e0 l\u2019\u00e9l\u00e9phant dans la pi\u00e8ce\u00a0: effectivement, le style de notre mod\u00e8le d\u2019essai n\u2019a rien d\u2019ordinaire. Le bolide a \u00e9t\u00e9 cr\u00e9\u00e9 par le d\u00e9partement FuoriSerie de Maserati, soit celui qui ag\u00eet \u00e0 titre d\u2019atelier de personnalisation pour les clients qui d\u00e9sirent obtenir des \u00e9l\u00e9ments uniques pour leur v\u00e9hicule.<\/p>\n<p>Cela-dit, bien qu\u2019on pourrait croire \u00e0 premi\u00e8re vu que la bagnole a \u00e9t\u00e9 habill\u00e9e aux couleurs de l\u2019Ukraine, il ne s\u2019agit que d\u2019une co\u00efncidence. \u00c0 vrai dire, la bagnole est \u00e0 l\u2019effigie des couleurs du drapeau de la ville natale de Maserati, soit Mod\u00e8ne. Le bleu et jaune qui couvrent la carrosserie fusionnent sur le toit du VUS afin de former le trident que l\u2019on retrouve sur le logo de Maserati, et ce dernier est bien \u00e9videmment de couleur jaune et bleu.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10791 size-full\" src=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2022\/09\/dsc00105-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1706\" \/><\/p>\n<p>Sans surprise, les regards qui se posaient sur nous lors de notre essai se faisaient nombreux. Bien que ce type de v\u00e9hicule soit chose commune dans la capitale mondiale de Maserati, Ferrari et autres, notre version \u00e0 l\u2019essai \u00e9tait pour le moins unique.<\/p>\n<p>Sinon, bien que le look de ce Levante GT impressionne beaucoup et laisse une impression que le v\u00e9hicule est dot\u00e9 de fortes performances, la version GT est davantage destin\u00e9e au confort et au luxe, alors que les versions \u00e0 motorisations plus costaudes sont les r\u00e9elles sportives de la gamme. Ainsi, notre Levante \u00e9tait d\u2019un confort tr\u00e8s respectable, alors que des si\u00e8ges bien rembourr\u00e9s, \u00e9lectroniquement ajustables et climatis\u00e9s f\u00fbt fix\u00e9s \u00e0 l\u2019avant. La suspension effectue quant \u00e0 elle un excellent travail lorsque vient le temps d\u2019absorber les imperfections de la route \u2013 elles se font nombreuses, dans des villages m\u00e9di\u00e9vaux -, mais elle demeure assez ferme pour inspirer confiance lors d\u2019une conduite plus agit\u00e9e.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10801 size-full\" src=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2022\/09\/dsc00111-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1706\" \/><\/p>\n<p><strong>Verdict final<\/strong><\/p>\n<p>Le Maserati Levante GT, avec sa motorisation hybride, est l\u2019un des premiers v\u00e9hicules de la marque \u00e0 emprunter le chemin de l\u2019\u00e9lectrification. Comme le franc dicton anglophone le dit, cette route est parsem\u00e9e d\u2019\u00e9cureuils aplatis. Certains r\u00e9ussirons \u00e0 le traverser, alors que d\u2019autres y laisserons leurs couleurs.<\/p>\n<p>Ainsi, le Levante GT que nous avons mis \u00e0 l\u2019essai a d\u00e9finitivement travers\u00e9 ce chemin. L\u2019impl\u00e9mentation de la technologie hybride est effectu\u00e9e dans les r\u00e8gles de l\u2019art, et le produit fini est sommes toute excellent. Difficile \u00e0 dire si ce mod\u00e8le se cr\u00e9era un chemin jusqu\u2019ici, mais chose certaine est que nous verrons en sol canadien d\u2019autres \u00e9cureuils aussi, voire sinon plus \u00e0 succ\u00e8s que ce Levante GT hybride.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Salon International de l\u2019Auto de Montr\u00e9al porte cette semaine bien son nom, puisqu\u2019il vous emm\u00e8ne en terre de Mod\u00e8ne, en Italie. C\u2019est en d\u00e9but de saison estivale que le Salon s\u2019est envol\u00e9 pour le Vieux Continent, et on a eu droit \u00e0 une balade \u00e0 bord d\u2019un VUS aux couleurs pour le moins flamboyantes\u00a0: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-5556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maserati Levante GT 2022 : La Dolce Vita &#8211; Salon de l&#039;Auto de Montr\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maserati Levante GT 2022 : La Dolce Vita &#8211; Salon de l&#039;Auto de Montr\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Le Salon International de l\u2019Auto de Montr\u00e9al porte cette semaine bien son nom, puisqu\u2019il vous emm\u00e8ne en terre de Mod\u00e8ne, en Italie. C\u2019est en d\u00e9but de saison estivale que le Salon s\u2019est envol\u00e9 pour le Vieux Continent, et on a eu droit \u00e0 une balade \u00e0 bord d\u2019un VUS aux couleurs pour le moins flamboyantes\u00a0: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon de l&#039;Auto de Montr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SalonAutoMontreal\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-01T22:30:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-25T20:45:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26160930\/dsc00100-scaled-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vincent Jobidon\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vincent Jobidon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/\"},\"author\":{\"name\":\"Vincent Jobidon\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#\\\/schema\\\/person\\\/4e97de2f6d08933f64b50ba85d56d30a\"},\"headline\":\"Maserati Levante GT 2022 : La Dolce Vita\",\"datePublished\":\"2022-09-01T22:30:03+00:00\",\"dateModified\":\"2024-10-25T20:45:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/\"},\"wordCount\":916,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26160930\\\/dsc00100-scaled-1-1.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/\",\"url\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/\",\"name\":\"Maserati Levante GT 2022 : La Dolce Vita &#8211; Salon de l&#039;Auto de Montr\u00e9al\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26160930\\\/dsc00100-scaled-1-1.jpg\",\"datePublished\":\"2022-09-01T22:30:03+00:00\",\"dateModified\":\"2024-10-25T20:45:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26160930\\\/dsc00100-scaled-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26160930\\\/dsc00100-scaled-1-1.jpg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/maserati-levante-gt-2022-la-dolce-vita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maserati Levante GT 2022 : La Dolce Vita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/\",\"name\":\"Salon de l'Auto de Montr\u00e9al\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#organization\",\"name\":\"Salon de l'Auto de Montr\u00e9al\",\"alternateName\":\"Salon de l'Auto\",\"url\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/19140732\\\/logo-salon-auto-mtl.webp\",\"contentUrl\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/19140732\\\/logo-salon-auto-mtl.webp\",\"width\":696,\"height\":696,\"caption\":\"Salon de l'Auto de Montr\u00e9al\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SalonAutoMontreal\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#\\\/schema\\\/person\\\/4e97de2f6d08933f64b50ba85d56d30a\",\"name\":\"Vincent Jobidon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g\",\"caption\":\"Vincent Jobidon\"},\"url\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/author\\\/vincent\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maserati Levante GT 2022 : La Dolce Vita &#8211; Salon de l&#039;Auto de Montr\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/","og_locale":"fr_FR","og_type":"article","og_title":"Maserati Levante GT 2022 : La Dolce Vita &#8211; Salon de l&#039;Auto de Montr\u00e9al","og_description":"Le Salon International de l\u2019Auto de Montr\u00e9al porte cette semaine bien son nom, puisqu\u2019il vous emm\u00e8ne en terre de Mod\u00e8ne, en Italie. C\u2019est en d\u00e9but de saison estivale que le Salon s\u2019est envol\u00e9 pour le Vieux Continent, et on a eu droit \u00e0 une balade \u00e0 bord d\u2019un VUS aux couleurs pour le moins flamboyantes\u00a0: [&hellip;]","og_url":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/","og_site_name":"Salon de l&#039;Auto de Montr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/SalonAutoMontreal\/","article_published_time":"2022-09-01T22:30:03+00:00","article_modified_time":"2024-10-25T20:45:34+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26160930\/dsc00100-scaled-1-1.jpg","type":"image\/jpeg"}],"author":"Vincent Jobidon","twitter_misc":{"\u00c9crit par":"Vincent Jobidon","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/#article","isPartOf":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/"},"author":{"name":"Vincent Jobidon","@id":"https:\/\/www.salonautomontreal.com\/fr\/#\/schema\/person\/4e97de2f6d08933f64b50ba85d56d30a"},"headline":"Maserati Levante GT 2022 : La Dolce Vita","datePublished":"2022-09-01T22:30:03+00:00","dateModified":"2024-10-25T20:45:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/"},"wordCount":916,"publisher":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26160930\/dsc00100-scaled-1-1.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/","url":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/","name":"Maserati Levante GT 2022 : La Dolce Vita &#8211; Salon de l&#039;Auto de Montr\u00e9al","isPartOf":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/#primaryimage"},"image":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26160930\/dsc00100-scaled-1-1.jpg","datePublished":"2022-09-01T22:30:03+00:00","dateModified":"2024-10-25T20:45:34+00:00","breadcrumb":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/#primaryimage","url":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26160930\/dsc00100-scaled-1-1.jpg","contentUrl":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26160930\/dsc00100-scaled-1-1.jpg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/maserati-levante-gt-2022-la-dolce-vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.salonautomontreal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Maserati Levante GT 2022 : La Dolce Vita"}]},{"@type":"WebSite","@id":"https:\/\/www.salonautomontreal.com\/fr\/#website","url":"https:\/\/www.salonautomontreal.com\/fr\/","name":"Salon de l'Auto de Montr\u00e9al","description":"","publisher":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salonautomontreal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salonautomontreal.com\/fr\/#organization","name":"Salon de l'Auto de Montr\u00e9al","alternateName":"Salon de l'Auto","url":"https:\/\/www.salonautomontreal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salonautomontreal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/11\/19140732\/logo-salon-auto-mtl.webp","contentUrl":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/11\/19140732\/logo-salon-auto-mtl.webp","width":696,"height":696,"caption":"Salon de l'Auto de Montr\u00e9al"},"image":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SalonAutoMontreal\/"]},{"@type":"Person","@id":"https:\/\/www.salonautomontreal.com\/fr\/#\/schema\/person\/4e97de2f6d08933f64b50ba85d56d30a","name":"Vincent Jobidon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g","caption":"Vincent Jobidon"},"url":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/author\/vincent\/"}]}},"_links":{"self":[{"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/posts\/5556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/comments?post=5556"}],"version-history":[{"count":0,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/posts\/5556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/media\/5208"}],"wp:attachment":[{"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/media?parent=5556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/categories?post=5556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/tags?post=5556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}