{"id":5504,"date":"2021-10-15T19:00:08","date_gmt":"2021-10-15T23:00:08","guid":{"rendered":"https:\/\/salonautomontreal.com\/genesis-gv80-2021-lart-de-se-distinguer\/"},"modified":"2024-10-28T09:52:44","modified_gmt":"2024-10-28T13:52:44","slug":"genesis-gv80-2021-lart-de-se-distinguer","status":"publish","type":"post","link":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/","title":{"rendered":"Genesis GV80 2021: L\u2019art de se distinguer"},"content":{"rendered":"<p>L\u2019industrie automobile est compos\u00e9e en grande partie d\u2019acteurs tr\u00e8s conservateurs : changer une recette chez un constructeur automobile, c\u2019est une chose qui ne se fait que tr\u00e8s rarement. \u00c0 vrai dire, si l\u2019industrie automobile ne subit pas de pression externe comme c\u2019est le cas avec l\u2019\u00e9lectrification des transports, alors rares se feront les changements apport\u00e9s que ce soit d\u2019un point de vue m\u00e9canique ou stylistique. Les produits commercialis\u00e9s par les manufacturiers ont un cycle de vie souvent tr\u00e8s long, alors qu\u2019on recycle des moteurs ici et l\u00e0, qu\u2019on am\u00e9liore ladite motorisation au fil des ans sans jamais la changer, qu\u2019on redessine quelques \u00e9l\u00e9ments esth\u00e9tiques ou qu\u2019on change quelque peu l\u2019apparence d\u2019un mod\u00e8le selon le march\u00e9 dans lequel on l\u2019implante (e.g. Europe vs Am\u00e9rique du Nord). Au final, par contre, c\u2019est presque toujours du pareil au m\u00eame.<\/p>\n<p>Ainsi, lorsque des constructeurs s\u2019aventurent en terrain plus risqu\u00e9, on se retrouve plus souvent qu\u2019autrement agr\u00e9ablement surpris. En faisant ainsi exception \u00e0 la r\u00e8gle, Genesis met de l\u2019avant des produits tr\u00e8s audacieux comme notre essai de la semaine, le Genesis GV80 2021, et laissez-nous vous dire que ce VUS interm\u00e9diaire de luxe ne passe pas inaper\u00e7u.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8718 size-full\" src=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2021\/10\/dsc-7161.jpg\" alt=\"\" width=\"1626\" height=\"1080\" \/><\/h2>\n<h2>Derri\u00e8re le volant<\/h2>\n<p>Se situant tout au sommet de la ligne des VUS chez Genesis, le GV80 se veut, avec la berline pleine grandeur G90, le mod\u00e8le porte-\u00e9tendard de la marque. Notre mod\u00e8le d\u2019essai se voulait la version \u00ab Prestige \u00bb et \u00e9tait muni d\u2019une motorisation \u00e0 6 cylindres turbocompress\u00e9e de 3.5 litres qui d\u00e9veloppe plus de 375 chevaux et 391 livres de couples, le tout jumel\u00e9 \u00e0 une transmission automatique \u00e0 8 rapports et \u00e0 un syst\u00e8me 4 roues motrices. Bien franchement, la motorisation offerte de s\u00e9rie, soit celle de 4 cylindres (2.5 litres) turbocompress\u00e9e qui produit 300 chevaux, est amplement suffisante pour les besoins de tous. Ce que la m\u00e9canique de notre version \u00e0 l\u2019essai apporte, par contre, c\u2019est une fluidit\u00e9 et une qui\u00e9tude qu\u2019il est difficile de retrouver avec la motorisation de 2.5 litres, et apr\u00e8s tout, n\u2019est-ce pas exactement cela que l\u2019on recherche dans un bolide qui d\u00e9borde d\u2019opulence et de luxe : le calme et la s\u00e9r\u00e9nit\u00e9? Qui plus est, la transmission automatique \u00e0 8 rapports est d\u2019une efficacit\u00e9 renversante : les changements de vitesse sont pratiquement imperceptibles tout en demeurant rapides, bien que non constants, lorsque notre pied s\u2019alourdit.<\/p>\n<p>Simplement, la motorisation de 6 cylindres vous offre une exp\u00e9rience conduite, voire passag\u00e8re, plus agr\u00e9able que sa contrepartie de 4 cylindres. Elle est moins bruyante, moins capricieuse et quelque peu plus performante. Elle est donc plus repr\u00e9sentative des autres aspects renversants du GV80, puisque ne d\u00e9trompez-vous pas, rien de ce bolide n\u2019est \u00ab ordinaire \u00bb.<\/p>\n<p>L\u2019histoire ne s\u2019arr\u00eate cependant pas encore ici, puisque le groupe motopropulseur n\u2019est pas l\u2019unique raison pour laquelle la conduite de ce sublime VUS cor\u00e9en est si int\u00e9ressante. Effectivement, le travail que la suspension et la direction effectuent y joue pour gros. Bien que notre mod\u00e8le d\u2019essai f\u00fbt muni de jantes d\u2019une grandeur de 22 pouces, qui n\u2019aidaient certainement pas au niveau de l\u2019absorption des imperfections de la route, le confort qui r\u00e9sulte de la qualit\u00e9 des composantes m\u00e9caniques de la suspension est tout simplement \u00e9poustouflant. La direction, quant \u00e0 elle, n\u2019a certainement pas pour but d\u2019\u00eatre d\u2019une pr\u00e9cision extr\u00eame ou de communiquer l\u2019\u00e9tat de la chauss\u00e9e. Plut\u00f4t, elle s\u2019assure de vous faire oublier le poids de 4,938 livres en vous offrant une exp\u00e9rience mielleuse et d\u00e9licate.<\/p>\n<p>Ainsi, le verdict des capacit\u00e9s m\u00e9caniques et dynamiques de notre GV80 est sans surprise : on priorise d\u2019abord le confort, puis on t\u00e2che de rendre l\u2019exp\u00e9rience conduite quelque peu plus sportive lorsque le conducteur le demande. Au final, par contre, c\u2019est le confort, la tranquillit\u00e9 et la constance que l\u2019on priorise chez Genesis, alors qu\u2019il est facile d\u2019observer le contraire chez la comp\u00e9tition.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8742 size-full\" src=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2021\/10\/dsc-7220.jpg\" alt=\"\" width=\"1626\" height=\"1080\" \/><\/h2>\n<h2>Look et habitacle<\/h2>\n<p>Si notre r\u00e9sum\u00e9 de la conduite du GV80 ne vous a pas convaincu, soyez sans crainte puisque c\u2019est ici que les choses se g\u00e2tent. Bien que la beaut\u00e9 d\u2019une chose soit d\u2019une subjectivit\u00e9 non discutable, certaines de ces choses semblent parfois \u00e9chapper \u00e0 cette v\u00e9rit\u00e9 et comme vous l\u2019aurez devin\u00e9, on s\u2019avance en affirmant que le VUS interm\u00e9diaire de luxe de Genesis semble \u00e9chapper \u00e0 ce dire.<\/p>\n<p>On ne se le cachera pas, le look ext\u00e9rieur semble tout droit calquer d\u2019un Bentley Bentayga, mais comme le fameux dicton nous le d\u00e9montre; \u00ab if you can\u2019t beat them, join them \u00bb. C\u2019est d\u2019ailleurs pile-poil ce qui s\u2019est pass\u00e9 ici, puisque le styliste en chef de Hyundai\/Genesis, Sangyup Lee, \u00e9tait \u00e0 l\u2019\u00e9poque \u00e0 l\u2019embauche du groupe Volkswagen, et donc en grande partie responsable du design chez Bentley. Ainsi, chapeau \u00e0 Genesis de ne pas craindre d\u2019emprunter des \u00e9l\u00e9ments stylistiques (ou des stylistes!) de marques \u00e9tablies depuis plus de 100 ans, puisqu\u2019apr\u00e8s tout, c\u2019est nous, les consommateurs, qui en b\u00e9n\u00e9ficions.<\/p>\n<p>Ceci dit, le look du GV80 est selon nous \u00e0 couper le souffle : il fait tourner des t\u00eates sans cesse, se distingue dans l\u2019oc\u00e9an de VUS qui foule nos routes, s\u2019apparente \u00e0 une voiture qui pourrait co\u00fbter jusqu\u2019\u00e0 4 fois le prix et fait r\u00e9ellement bonne allure ind\u00e9pendamment de sa sp\u00e9cification.<\/p>\n<p>L\u2019habitacle, par contre, est le r\u00e9el point central du GV80. Aussit\u00f4t que l\u2019on prend place \u00e0 bord, on comprend o\u00f9 ont \u00e9t\u00e9 d\u00e9pens\u00e9s les pr\u00e9cieux dollars du budget mis en place afin de construire ce v\u00e9hicule. Un cuir aux teintes prunes recouvre presque chaque recoin de l\u2019habitacle, alors que le plafond et les piliers sont rev\u00eatus de su\u00e8de tr\u00e8s plaisant au toucher. Un \u00e9cran tactile centrale de 14.5 pouces saute aux yeux, et le levier de vitesse en format roulette impressionne par son design \u00e0 mi-chemin entre le contemporain et le baroque.<\/p>\n<p>Les fonctionnalit\u00e9s techniques\/technos sont quant \u00e0 elles plus nombreuses que l\u2019on peut les compter, mais quelques-unes ont su retenir notre attention. On parle tout d\u2019abord du syst\u00e8me d\u2019aide \u00e0 la conduite \u00e0 la fine pointe de la technologie : r\u00e9gulateur de vitesse intelligent et contr\u00f4le autonome de la direction, ce syst\u00e8me d\u2019aide \u00e0 la conduite est vraiment au sommet de son art. Un trajet Montr\u00e9al-Ottawa effectu\u00e9 en empruntant l\u2019autoroute 40 s\u2019est av\u00e9r\u00e9 \u00e9merveillant, puisque sur une distance de pr\u00e8s de 200 kilom\u00e8tres, nous avons d\u00fb interagir avec le volant moins d\u2019une dizaine de fois. Sinon, le syst\u00e8me audio est d\u2019une clart\u00e9 et d\u2019une puissance in\u00e9gal\u00e9e par rapport au prix de vente de notre v\u00e9hicule. D\u2019ailleurs, les 85,000$ demand\u00e9s pour notre v\u00e9hicule d\u2019essai sont certes \u00e9lev\u00e9s, mais un v\u00e9hicule semblablement \u00e9quip\u00e9 chez la comp\u00e9tition allemande se verrait afficher un prix de vente bien au-del\u00e0 des 100,000$. Ici repose d\u2019ailleurs le principal avantage concurrentiel de Genesis : le luxe et le prestige, mais \u00e0 prix \u00ab abordable \u00bb.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8716 size-full\" src=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2021\/10\/dsc-7152.jpg\" alt=\"\" width=\"1626\" height=\"1080\" \/><\/h2>\n<h2>Verdict final<\/h2>\n<p>Pas pour rien que le GV80 f\u00fbt nomm\u00e9 VUS de l\u2019ann\u00e9e par l\u2019AJAC pour l\u2019ann\u00e9e 2021. Ce bolide est un coup de circuit pour Genesis, qui tente de se d\u00e9faire de son identit\u00e9 \u00ab Hyundai \u00bb afin de s\u2019implanter comme joueur s\u00e9rieux dans son march\u00e9 respectif. Notre version \u00e0 l\u2019essai est la plus impressionnante des versions offertes, mais la version d\u2019entr\u00e9e de gamme qui se d\u00e9taille 64,500$, soit 20,000$ (ou bien l\u2019\u00e9quivalent de 2 Chevrolet Spark flambant neuves!), est d\u2019autant plus all\u00e9chante et m\u00e9rite fortement d\u2019\u00eatre consid\u00e9r\u00e9e. Un nouveau joueur est parmi nous, et ne vous attendez pas \u00e0 le voir baisser les bras pour les ann\u00e9es \u00e0 venir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019industrie automobile est compos\u00e9e en grande partie d\u2019acteurs tr\u00e8s conservateurs : changer une recette chez un constructeur automobile, c\u2019est une chose qui ne se fait que tr\u00e8s rarement. \u00c0 vrai dire, si l\u2019industrie automobile ne subit pas de pression externe comme c\u2019est le cas avec l\u2019\u00e9lectrification des transports, alors rares se feront les changements apport\u00e9s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-5504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Genesis GV80 2021: L\u2019art de se distinguer &#8211; Salon de l&#039;Auto de Montr\u00e9al<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Genesis GV80 2021: L\u2019art de se distinguer &#8211; Salon de l&#039;Auto de Montr\u00e9al\" \/>\n<meta property=\"og:description\" content=\"L\u2019industrie automobile est compos\u00e9e en grande partie d\u2019acteurs tr\u00e8s conservateurs : changer une recette chez un constructeur automobile, c\u2019est une chose qui ne se fait que tr\u00e8s rarement. \u00c0 vrai dire, si l\u2019industrie automobile ne subit pas de pression externe comme c\u2019est le cas avec l\u2019\u00e9lectrification des transports, alors rares se feront les changements apport\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon de l&#039;Auto de Montr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SalonAutoMontreal\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T23:00:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T13:52:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26155837\/dsc-7189.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1626\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vincent Jobidon\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vincent Jobidon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/\"},\"author\":{\"name\":\"Vincent Jobidon\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#\\\/schema\\\/person\\\/4e97de2f6d08933f64b50ba85d56d30a\"},\"headline\":\"Genesis GV80 2021: L\u2019art de se distinguer\",\"datePublished\":\"2021-10-15T23:00:08+00:00\",\"dateModified\":\"2024-10-28T13:52:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/\"},\"wordCount\":1362,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26155837\\\/dsc-7189.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/\",\"url\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/\",\"name\":\"Genesis GV80 2021: L\u2019art de se distinguer &#8211; Salon de l&#039;Auto de Montr\u00e9al\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26155837\\\/dsc-7189.jpg\",\"datePublished\":\"2021-10-15T23:00:08+00:00\",\"dateModified\":\"2024-10-28T13:52:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26155837\\\/dsc-7189.jpg\",\"contentUrl\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26155837\\\/dsc-7189.jpg\",\"width\":1626,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/genesis-gv80-2021-lart-de-se-distinguer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Genesis GV80 2021: L\u2019art de se distinguer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/\",\"name\":\"Salon de l'Auto de Montr\u00e9al\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#organization\",\"name\":\"Salon de l'Auto de Montr\u00e9al\",\"alternateName\":\"Salon de l'Auto\",\"url\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/19140732\\\/logo-salon-auto-mtl.webp\",\"contentUrl\":\"https:\\\/\\\/assets.salonautomontreal.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/19140732\\\/logo-salon-auto-mtl.webp\",\"width\":696,\"height\":696,\"caption\":\"Salon de l'Auto de Montr\u00e9al\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SalonAutoMontreal\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/#\\\/schema\\\/person\\\/4e97de2f6d08933f64b50ba85d56d30a\",\"name\":\"Vincent Jobidon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g\",\"caption\":\"Vincent Jobidon\"},\"url\":\"https:\\\/\\\/www.salonautomontreal.com\\\/fr\\\/chroniques-passionne\\\/author\\\/vincent\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Genesis GV80 2021: L\u2019art de se distinguer &#8211; Salon de l&#039;Auto de Montr\u00e9al","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/","og_locale":"fr_FR","og_type":"article","og_title":"Genesis GV80 2021: L\u2019art de se distinguer &#8211; Salon de l&#039;Auto de Montr\u00e9al","og_description":"L\u2019industrie automobile est compos\u00e9e en grande partie d\u2019acteurs tr\u00e8s conservateurs : changer une recette chez un constructeur automobile, c\u2019est une chose qui ne se fait que tr\u00e8s rarement. \u00c0 vrai dire, si l\u2019industrie automobile ne subit pas de pression externe comme c\u2019est le cas avec l\u2019\u00e9lectrification des transports, alors rares se feront les changements apport\u00e9s [&hellip;]","og_url":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/","og_site_name":"Salon de l&#039;Auto de Montr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/SalonAutoMontreal\/","article_published_time":"2021-10-15T23:00:08+00:00","article_modified_time":"2024-10-28T13:52:44+00:00","og_image":[{"width":1626,"height":1080,"url":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26155837\/dsc-7189.jpg","type":"image\/jpeg"}],"author":"Vincent Jobidon","twitter_misc":{"\u00c9crit par":"Vincent Jobidon","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/#article","isPartOf":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/"},"author":{"name":"Vincent Jobidon","@id":"https:\/\/www.salonautomontreal.com\/fr\/#\/schema\/person\/4e97de2f6d08933f64b50ba85d56d30a"},"headline":"Genesis GV80 2021: L\u2019art de se distinguer","datePublished":"2021-10-15T23:00:08+00:00","dateModified":"2024-10-28T13:52:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/"},"wordCount":1362,"publisher":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26155837\/dsc-7189.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/","url":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/","name":"Genesis GV80 2021: L\u2019art de se distinguer &#8211; Salon de l&#039;Auto de Montr\u00e9al","isPartOf":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/#primaryimage"},"image":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26155837\/dsc-7189.jpg","datePublished":"2021-10-15T23:00:08+00:00","dateModified":"2024-10-28T13:52:44+00:00","breadcrumb":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/#primaryimage","url":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26155837\/dsc-7189.jpg","contentUrl":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/09\/26155837\/dsc-7189.jpg","width":1626,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/genesis-gv80-2021-lart-de-se-distinguer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.salonautomontreal.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Genesis GV80 2021: L\u2019art de se distinguer"}]},{"@type":"WebSite","@id":"https:\/\/www.salonautomontreal.com\/fr\/#website","url":"https:\/\/www.salonautomontreal.com\/fr\/","name":"Salon de l'Auto de Montr\u00e9al","description":"","publisher":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salonautomontreal.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salonautomontreal.com\/fr\/#organization","name":"Salon de l'Auto de Montr\u00e9al","alternateName":"Salon de l'Auto","url":"https:\/\/www.salonautomontreal.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salonautomontreal.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/11\/19140732\/logo-salon-auto-mtl.webp","contentUrl":"https:\/\/assets.salonautomontreal.com\/wp-content\/uploads\/2024\/11\/19140732\/logo-salon-auto-mtl.webp","width":696,"height":696,"caption":"Salon de l'Auto de Montr\u00e9al"},"image":{"@id":"https:\/\/www.salonautomontreal.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SalonAutoMontreal\/"]},{"@type":"Person","@id":"https:\/\/www.salonautomontreal.com\/fr\/#\/schema\/person\/4e97de2f6d08933f64b50ba85d56d30a","name":"Vincent Jobidon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7d570823878edf018bf10380c4b4a67d569c5ab396d63c48b8c275d3ad5cc79?s=96&d=mm&r=g","caption":"Vincent Jobidon"},"url":"https:\/\/www.salonautomontreal.com\/fr\/chroniques-passionne\/author\/vincent\/"}]}},"_links":{"self":[{"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/posts\/5504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/comments?post=5504"}],"version-history":[{"count":0,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/posts\/5504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/media\/4137"}],"wp:attachment":[{"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/media?parent=5504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/categories?post=5504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salonautomontreal.com\/fr\/wp-json\/wp\/v2\/tags?post=5504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}